{"id":67379,"date":"2016-11-18T13:00:33","date_gmt":"2016-11-18T12:00:33","guid":{"rendered":"https:\/\/vosgesinfo.fr\/epinalinfo\/2016\/11\/primaire-ouverte-de-droite-centre-localisation-regroupement-bureaux\/"},"modified":"2016-11-18T13:00:33","modified_gmt":"2016-11-18T12:00:33","slug":"primaire-ouverte-de-droite-centre-localisation-regroupement-bureaux","status":"publish","type":"post","link":"https:\/\/vosgesinfo.fr\/epinalinfo\/2016\/11\/primaire-ouverte-de-droite-centre-localisation-regroupement-bureaux\/","title":{"rendered":"Primaire ouverte de la Droite et du Centre &#8211; Localisation et regroupement des bureaux"},"content":{"rendered":"<p><strong><a href=\"http:\/\/epinalinfos.fr\/2016\/10\/gerardmer-elections-departementales-binome-valentinpoirot-sort-tete-4189-voix\/vote\/\" rel=\"attachment wp-att-101025\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-101025\" src=\"\/2016\/10\/vote.jpg\" alt=\"vote\" width=\"640\" height=\"360\" \/><\/a>Le premier tour de la primaire de la droite et du centre aura lieu ce dimanche 20\u00a0novembre. Qui peut voter? O\u00f9 trouver mon bureau de vote ? Ses horaires d\u2019ouverture ? Comment se passe concr\u00e8tement le vote ? Vous trouverez toutes les r\u00e9ponses \u00e0 vos interrogations ci-dessous&#8230;<\/strong><\/p>\n<p>Les \u00e9lecteurs, et au premier lieu les sympathisants de la droite et du centre, sont invit\u00e9s \u00e0 venir choisir leur candidat \u00e0 la\u00a0<a href=\"http:\/\/election-presidentielle.linternaute.com\/\">pr\u00e9sidentielle 2017<\/a>. Le premier tour de ce scrutin aura lieu ce dimanche 20\u00a0novembre, et le second le dimanche 27 novembre.<\/p>\n<p><strong><u>Qui peut voter\u00a0?<\/u><\/strong><\/p>\n<p><strong>\u00a0Tous les \u00e9lecteurs inscrits sur les listes au 31\u00a0d\u00e9cembre 2015<\/strong> pourront,\u00a0s&rsquo;ils le souhaitent, se rendre dans un bureau de vote, dans leur commune, ou d&rsquo;une commune voisine.<\/p>\n<p><strong><u>O\u00f9 trouver mon bureau de vote ?<\/u><\/strong><\/p>\n<p>Ce sont\u00a010\u00a0228\u00a0bureaux de vote qui ouvriront ce dimanche, dont <strong><u>64<\/u><\/strong><strong><u> dans le d\u00e9partement des Vosges.\u00a0<\/u><\/strong><\/p>\n<p><strong><u>2 solutions pour trouver son bureau de vote sont propos\u00e9es\u00a0:<\/u><\/strong><\/p>\n<ul>\n<li><strong><u>Le site d\u00e9di\u00e9 \u00e0 la primaire<\/u><\/strong> <strong>liste l\u2019int\u00e9gralit\u00e9 des 10\u00a0228\u00a0bureaux par d\u00e9partement\u00a0en mettant \u00e0 disposition un moteur de recherche permettant de<\/strong><strong>trouver un bureau de vote \u00e0 partir de son adresse de r\u00e9sidence\u00a0: <\/strong><a href=\"http:\/\/primaire2016.us13.list-manage2.com\/track\/click?u=e3fbc2714e71807e9f1c2dc80&amp;id=593734c4fc&amp;e=909f1d4e7b\">monbureau.primaire2016.org<\/a><\/li>\n<\/ul>\n<ul>\n<li><strong><u>Un num\u00e9ro d&rsquo;information<\/u><\/strong> <strong>a \u00e9t\u00e9 mis en place pour tout renseignement sur les lieux du vote<\/strong>: <u>08 21\u00a020\u00a020 16<\/u>\u00a0 (0,12\u00a0euro\/minute).<\/li>\n<\/ul>\n<p><strong>\u00a0<\/strong><strong>Si vous habitez dans une commune qui ne dispose pas de bureau de vote pour la primaire de la droite<\/strong>, <u>2 solutions<\/u>\u00a0:<\/p>\n<ul>\n<li><strong><u>1<\/u><\/strong><u> soit vous \u00eates, comme pour toutes les \u00e9lections nationales, rattach\u00e9(e) \u00e0 un bureau de vote en fonction de votre adresse de r\u00e9sidence<\/u> &#8211; une \u00e9cole, mairie ou annexe de celle-ci -.<\/li>\n<\/ul>\n<p>Il est probable que ce bureau de vote \u00ab\u00a0de rattachement\u00a0\u00bb soit\u00a0 celui o\u00f9 vous irez voter \u00e0 la primaire de la droite si vous en avez l&rsquo;intention.<\/p>\n<p><strong><u>Si tel n\u2019est le cas, se reporter au point n\u00b02<\/u><\/strong><\/p>\n<p><strong><u>2<\/u><\/strong><u> soit votre bureau de vote habituel n&rsquo;a pas \u00e9t\u00e9 mobilis\u00e9 pour cette primaire\u00a0et a par cons\u00e9quent \u00e9t\u00e9 rattach\u00e9(e) \u00e0 un bureau de vote, m\u00eame si votre commune n\u2019en compte aucun<\/u>.<\/p>\n<p>le meilleur moyen de connaitre l&rsquo;adresse exacte o\u00f9 vous pourrez voter est de se connecter au site officiel de la primaire et de taper son adresse dans le moteur de recherche.<\/p>\n<p><strong><u>Les horaires d\u2019ouverture des bureaux de vote ?<\/u><\/strong><\/p>\n<p><strong><u>\u00a0<\/u><\/strong><strong><u>Tous les bureaux de vote ouvriront \u00e0\u00a008h00 et fermeront\u00a0\u00e0 19h00<\/u><\/strong><strong>, <\/strong>ceci afin d\u2019\u00e9viter le d\u00e9calage dans les d\u00e9pouillements et la fuite des premiers chiffres.<\/p>\n<p><strong><u>Et au niveau pratique, dans le bureau de vote ?<\/u><\/strong><\/p>\n<p><strong><u>\u00a0<\/u><\/strong><strong><u>Une fois dans le bureau de vote, la marche \u00e0 suivre est la suivante<\/u><\/strong><u>\u00a0:<\/u><\/p>\n<ul>\n<li><strong><u>S\u2019identifier en pr\u00e9sentant une pi\u00e8ce nationale d&rsquo;identit\u00e9<\/u><\/strong> <u>et \u00e9videmment \u00eatre inscrit sur les listes \u00e9lectorales au 31\u00a0d\u00e9cembre 2015<\/u>.<\/li>\n<\/ul>\n<p><u>Par ailleurs les\u00a0mineurs qui auront 18\u00a0ans \u00e0 la date de l&rsquo;\u00e9lection pr\u00e9sidentielle 2017 pourront voter<\/u>, <strong>sous r\u00e9serve d\u2019avoir effectu\u00e9 une pr\u00e9inscription arr\u00eat\u00e9e au 16.10.2016<\/strong>.<\/p>\n<ul>\n<li><strong><u>S\u2019\u2019acquitter de 2\u00a0euros par tour <\/u><\/strong><strong><u>pour participer aux frais d&rsquo;organisation de la primaire<\/u><\/strong> (soit 4\u00a0euros pour ceux qui voteraient lors des deux tours)<\/li>\n<\/ul>\n<ul>\n<li><strong><u>Certifier de leur adh\u00e9sion aux valeurs de la droite <\/u><\/strong><strong><u>en signant de leur main la phrase suivante<\/u><\/strong>:\u00a0\u00ab\u00a0Je partage les valeurs r\u00e9publicaines de la droite et du centre et je m&rsquo;engage pour l&rsquo;alternance afin de r\u00e9ussir le redressement de la France\u00a0\u00bb.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong><u>IMPORTANT<\/u><\/strong>\u00a0: <strong>le vote par procuration n&rsquo;est pas possible pour ce scrutin <\/strong><\/p>\n<p><strong>Les premiers\u00a0<\/strong><a href=\"http:\/\/www.linternaute.com\/actualite\/politique\/1268009-primaire-a-droite-le-resultat-des-sondages-encourageant-pour-fillon-juppe-en-baisse\/#resultat-primaire-droite\"><strong>r\u00e9sultats de la primaire de la droite<\/strong><\/a><strong>\u00a0seront connus dans la soir\u00e9e, vers 20h30, et seront ensuite mis \u00e0 jours toutes les 15\u00a0minutes jusqu&rsquo;au r\u00e9sultat d\u00e9finitif.<\/strong><\/p>\n<p><strong><u>Bureaux Primaire \u2013 Circo 1\u00a0: 16<\/u><\/strong><\/p>\n<p><strong><u>\u00a0<\/u><\/strong><\/p>\n<p><strong>1 EPINAL <\/strong>&#8211; BOURSE DU TRAVAIL &#8211; 4 RUE ARISTIDE BRIAND<\/p>\n<p><u>Si vous votez habituellement dans un des bureaux de vote suivants\u00a0:<\/u><u> <strong>H\u00f4tel de Ville, Ambrail, Ravel, Cl\u00e9menceau, Tranch\u00e9e de Docelles\u00a0 ou Bourse du Travail<\/strong><\/u><\/p>\n<p><strong><u>\u00a0<\/u><\/strong><\/p>\n<p><strong>2 EPINAL <\/strong>&#8211; GROUPE SCOLAIRE DE LA LOGE BLANCHE &#8211; 9 RUE DES FUSILL\u00c9S DE LA RESISTANCE<\/p>\n<p><u>Si vous votez habituellement dans un des bureaux de vote suivants\u00a0:<\/u><u> <strong>Luc Escande, Jacquard Centre social + salle animation, Rimey, Centre Social Saint Laurent, Vieux Saint Laurent, Champbeauvert, Groupe Scolaire de la Loge Blanche<\/strong><\/u><\/p>\n<p><strong><u>\u00a0<\/u><\/strong><\/p>\n<p><strong>3 EPINAL\u00a0 <\/strong>&#8211; GROUPE SCOLAIRE JEAN MAC\u00c9 &#8211; 15 RUE CHARLES PERRAULT<\/p>\n<p><u>Si vous votez habituellement dans un des bureaux de vote suivants\u00a0:<\/u><u> <strong>Salle de spectacle Plateau de la Justice, Epinettes, Groupe Scolaire Jean Mac\u00e9<\/strong><\/u><\/p>\n<p><strong><u>\u00a0<\/u><\/strong><\/p>\n<p><strong>4 EPINAL\u00a0 <\/strong>&#8211; GROUPE SCOLAIRE VICTOR HUGO &#8211; 2 AVENUE VICTOR HUGO<\/p>\n<p><u>Si vous votez habituellement dans un des bureaux de vote suivants\u00a0: <\/u><strong><u>Durkheim, \u00a0Isa\u00ef, 149<sup>\u00e8me<\/sup>, Paul Emile Victor, Groupe Scolaire Victor Hugo<\/u><\/strong><\/p>\n<p><strong><u>\u00a0<\/u><\/strong><\/p>\n<p><strong>5\u00a0 EPINAL &#8211; <\/strong>GROUPE SCOLAIRE SAUT LE CERF &#8211; 4 RUE DU COUARAIL<\/p>\n<p><u>Si vous votez habituellement dans un des bureaux de vote suivants\u00a0:<\/u><u> <strong>Louis Pergaud, L\u00e9o Lagrange ou Groupe Scolaire Saut le Cerf<\/strong><\/u><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>6 GOLBEY<\/strong> &#8211; SALLE DE R\u00c9UNION &#8211; : RUE DE GRANRUPT<br \/>\n<u>Si vous votez habituellement dans un des 7 bureaux de vote de <strong>Golbey<\/strong><\/u><\/p>\n<p>&nbsp;<\/p>\n<p><strong>7 CHANTRAINE<\/strong> &#8211; MAISON DES BROSSES &#8211; : 45 RUE JULES FERRY<br \/>\n<u>Si vous votez habituellement dans un des 3 bureaux de vote de <strong>Chantraine<\/strong> ou un des 2 bureaux de vote de <strong>Les Forges<\/strong><\/u><\/p>\n<p><u>\u00a0<\/u><\/p>\n<p><strong>8 THAON LES VOSGES<\/strong> &#8211; ARCHE BERNADETTE : : 1 AVENUE DES FUSILL\u00c9S<br \/>\n<u>Si vous votez habituellement dans un des 7 bureaux de vote de <strong>Thaon les Vosges<\/strong><br \/>\nOu \u00e0 <strong>Sercoeur<\/strong>, <strong>Girmont<\/strong>, <strong>Oncourt<\/strong>, <strong>Bayecourt<\/strong>, <strong>Chavelot<\/strong><\/u><\/p>\n<p>&nbsp;<\/p>\n<p><strong>9 DARNIEULLES<\/strong> \u2013 MAIRIE : 374 RUE DE MIRECOURT<br \/>\n<u>Si vous votez habituellement dans un des 2 bureaux de vote de <strong>Darnieulles<\/strong><br \/>\nOu un des 2 bureaux de vote d\u2019<strong>Uxegney &#8211; Sanchey<\/strong> ou \u00e0 <strong>Chaumousey, Dommartin aux Bois , Renauvoid, Mazeley, Gigney, Fomerey , Dom\u00e8vre sur Avi\u00e8re, Girancourt<\/strong><\/u><\/p>\n<p>&nbsp;<\/p>\n<p><strong>10 RAMBERVILLERS<\/strong> &#8211; SALLE DES F\u00caTES : RUE JULES FERRY<br \/>\n<u>Si vous votez habituellement dans un des 4 bureaux de vote de <strong>Rambervillers<\/strong><br \/>\nOu \u00e0 <strong>Moyenmont, Romont, Vom\u00e9court , Bult, Saint-Gorgon, Jeanm\u00e9nil, Housseras, Br\u00fb , Roville aux Ch\u00eanes, Autrey,<\/strong><\/u><\/p>\n<p>&nbsp;<\/p>\n<p><strong>11 XERTIGNY<\/strong> \u2013 MAIRIE : 2 CANTON DE FIRMINY<br \/>\n<u>Si vous votez habituellement dans un 5 bureaux de vote de <strong>Xertigny<\/strong><br \/>\nOu \u00e0 <strong>Le Clerjus, La Chapelle aux Bois, Uzemain, Charmois l\u2019Orgueilleux<\/strong> ,<\/u><\/p>\n<p>&nbsp;<\/p>\n<p><strong>12 NOMEXY<\/strong> &#8211; MAISON DES ASSOCIATIONS : RUE DU DOCTEUR LOUVARD<br \/>\n<u>Si vous votez habituellement \u00e0 <strong>Nomexy,<\/strong> <strong>Frizon, Vaxoncourt, Dom\u00e8vre sur Durbion, Pallegney Badm\u00e9nil aux Bois, Zincourt, Hadigny les Verri\u00e8res, Ch\u00e2tel sur Moselle, Villoncourt, Igney<\/strong><\/u><\/p>\n<p>&nbsp;<\/p>\n<p><strong>13 REHAINCOURT<\/strong> \u2013 MAIRIE : PLACE DE LA MAIRIE<br \/>\n<u>Si vous votez habituellement \u00e0 Rehaincourt, <strong>Moriville Damas aux Bois Haillainville Ortoncourt Fauconcourt Clezentaine, Saint Genest, Deinvillers, Hardancourt, Saint Maurice sur Mortagne<\/strong><\/u><\/p>\n<p><u>\u00a0<\/u><\/p>\n<p><strong>14 ARCHES<\/strong> &#8211; ESPACE ASSOCIATIF : RUE DE LA COLOMBI\u00c8RE<br \/>\n<u>Si vous votez habituellement \u00e0 <strong>La Baffe Archettes Hadol Dounoux Dinoz\u00e9 Urim\u00e9nil<\/strong><\/u><\/p>\n<p>&nbsp;<\/p>\n<p><strong>15 DEYVILLERS<\/strong> \u2013 MAIRIE : 2 RUE DE LORRAINE<br \/>\n<u>Si vous votez habituellement \u00e0 <strong>Vaud\u00e9ville, Jeuxey, Dignonville, Longchamp, Dogneville<\/strong><\/u><\/p>\n<p><u>\u00a0<\/u><\/p>\n<p><strong>16 M\u00c9NIL SUR BELVITTE<\/strong> \u2013 MAIRIE : 10 ROUTE DE RAMBERVILLERS<br \/>\n<u>Si vous votez habituellement \u00e0 <strong>Saint-Benoit la Chipotte, Sainte Barbe, Anglemont, Nossoncourt \u00a0Bazien \u00a0Donci\u00e8res, Xaff\u00e9villers, M\u00e9narmont, Saint-Pierremont, Domptail<\/strong><\/u><\/p>\n<p>Haut du formulaire<\/p>\n<p>Bas du formulaire<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le premier tour de la primaire de la droite et du centre aura lieu ce dimanche 20\u00a0novembre. Qui peut voter? [&hellip;]<\/p>\n","protected":false},"author":52,"featured_media":12891,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,5],"tags":[9481,9482,9483],"class_list":["post-67379","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-la-une","category-vosges","tag-bureaux-de-vote","tag-localisation","tag-primaire-ouverte-de-la-droite-et-du-centre"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Primaire ouverte de la Droite et du Centre - Localisation et regroupement des bureaux - Epinal Info<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vosgesinfo.fr\/epinalinfo\/2016\/11\/primaire-ouverte-de-droite-centre-localisation-regroupement-bureaux\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Primaire ouverte de la Droite et du Centre - Localisation et regroupement des bureaux - Epinal Info\" \/>\n<meta name=\"twitter:description\" content=\"Le premier tour de la primaire de la droite et du centre aura lieu ce dimanche 20\u00a0novembre. Qui peut voter? [&hellip;]\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/3\/2017\/04\/vote.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@VosgesInfo88\" \/>\n<meta name=\"twitter:site\" content=\"@VosgesInfo88\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"C.K.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/vosgesinfo.fr\/epinalinfo\/2016\/11\/primaire-ouverte-de-droite-centre-localisation-regroupement-bureaux\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/vosgesinfo.fr\/epinalinfo\/2016\/11\/primaire-ouverte-de-droite-centre-localisation-regroupement-bureaux\/\"},\"author\":{\"name\":\"C.K.\",\"@id\":\"https:\/\/vosgesinfo.fr\/epinalinfo\/#\/schema\/person\/6f9a650eeea99d969b6c4ab78fccbe81\"},\"headline\":\"Primaire ouverte de la Droite et du Centre &#8211; Localisation et regroupement des bureaux\",\"datePublished\":\"2016-11-18T12:00:33+00:00\",\"dateModified\":\"2016-11-18T12:00:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/vosgesinfo.fr\/epinalinfo\/2016\/11\/primaire-ouverte-de-droite-centre-localisation-regroupement-bureaux\/\"},\"wordCount\":1121,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/vosgesinfo.fr\/epinalinfo\/#organization\"},\"image\":{\"@id\":\"https:\/\/vosgesinfo.fr\/epinalinfo\/2016\/11\/primaire-ouverte-de-droite-centre-localisation-regroupement-bureaux\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/3\/2017\/04\/vote.jpg\",\"keywords\":[\"bureaux de vote\",\"Localisation\",\"Primaire ouverte de la Droite et du Centre\"],\"articleSection\":[\"A la Une\",\"Vosges\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/vosgesinfo.fr\/epinalinfo\/2016\/11\/primaire-ouverte-de-droite-centre-localisation-regroupement-bureaux\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/vosgesinfo.fr\/epinalinfo\/2016\/11\/primaire-ouverte-de-droite-centre-localisation-regroupement-bureaux\/\",\"url\":\"https:\/\/vosgesinfo.fr\/epinalinfo\/2016\/11\/primaire-ouverte-de-droite-centre-localisation-regroupement-bureaux\/\",\"name\":\"Primaire ouverte de la Droite et du Centre - Localisation et regroupement des bureaux - Epinal Info\",\"isPartOf\":{\"@id\":\"https:\/\/vosgesinfo.fr\/epinalinfo\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/vosgesinfo.fr\/epinalinfo\/2016\/11\/primaire-ouverte-de-droite-centre-localisation-regroupement-bureaux\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/vosgesinfo.fr\/epinalinfo\/2016\/11\/primaire-ouverte-de-droite-centre-localisation-regroupement-bureaux\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/3\/2017\/04\/vote.jpg\",\"datePublished\":\"2016-11-18T12:00:33+00:00\",\"dateModified\":\"2016-11-18T12:00:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/vosgesinfo.fr\/epinalinfo\/2016\/11\/primaire-ouverte-de-droite-centre-localisation-regroupement-bureaux\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/vosgesinfo.fr\/epinalinfo\/2016\/11\/primaire-ouverte-de-droite-centre-localisation-regroupement-bureaux\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/vosgesinfo.fr\/epinalinfo\/2016\/11\/primaire-ouverte-de-droite-centre-localisation-regroupement-bureaux\/#primaryimage\",\"url\":\"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/3\/2017\/04\/vote.jpg\",\"contentUrl\":\"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/3\/2017\/04\/vote.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/vosgesinfo.fr\/epinalinfo\/2016\/11\/primaire-ouverte-de-droite-centre-localisation-regroupement-bureaux\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/vosgesinfo.fr\/epinalinfo\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Primaire ouverte de la Droite et du Centre &#8211; Localisation et regroupement des bureaux\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/vosgesinfo.fr\/epinalinfo\/#website\",\"url\":\"https:\/\/vosgesinfo.fr\/epinalinfo\/\",\"name\":\"Epinal Info\",\"description\":\"Toute l&#039;actualit\u00e9 d&#039;\u00c9pinal\",\"publisher\":{\"@id\":\"https:\/\/vosgesinfo.fr\/epinalinfo\/#organization\"},\"alternateName\":\"Toute l'actualit\u00e9 d'\u00c9pinal\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/vosgesinfo.fr\/epinalinfo\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/vosgesinfo.fr\/epinalinfo\/#organization\",\"name\":\"Epinal Info\",\"url\":\"https:\/\/vosgesinfo.fr\/epinalinfo\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/vosgesinfo.fr\/epinalinfo\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/3\/2023\/08\/logo-epinalinfos.svg\",\"contentUrl\":\"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/3\/2023\/08\/logo-epinalinfos.svg\",\"width\":1,\"height\":1,\"caption\":\"Epinal Info\"},\"image\":{\"@id\":\"https:\/\/vosgesinfo.fr\/epinalinfo\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Epinalinfos\",\"https:\/\/x.com\/VosgesInfo88\",\"https:\/\/www.youtube.com\/@vosgesinfo\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/vosgesinfo.fr\/epinalinfo\/#\/schema\/person\/6f9a650eeea99d969b6c4ab78fccbe81\",\"name\":\"C.K.\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/vosgesinfo.fr\/epinalinfo\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/48e3fc7f8421ba8942be6b74a2b7f014ca39bc00dece156b7a8e098ae7dc87bf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/48e3fc7f8421ba8942be6b74a2b7f014ca39bc00dece156b7a8e098ae7dc87bf?s=96&d=mm&r=g\",\"caption\":\"C.K.\"},\"url\":\"https:\/\/vosgesinfo.fr\/epinalinfo\/author\/celia-k-n\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Primaire ouverte de la Droite et du Centre - Localisation et regroupement des bureaux - Epinal Info","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vosgesinfo.fr\/epinalinfo\/2016\/11\/primaire-ouverte-de-droite-centre-localisation-regroupement-bureaux\/","twitter_card":"summary_large_image","twitter_title":"Primaire ouverte de la Droite et du Centre - Localisation et regroupement des bureaux - Epinal Info","twitter_description":"Le premier tour de la primaire de la droite et du centre aura lieu ce dimanche 20\u00a0novembre. Qui peut voter? [&hellip;]","twitter_image":"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/3\/2017\/04\/vote.jpg","twitter_creator":"@VosgesInfo88","twitter_site":"@VosgesInfo88","twitter_misc":{"\u00c9crit par":"C.K.","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vosgesinfo.fr\/epinalinfo\/2016\/11\/primaire-ouverte-de-droite-centre-localisation-regroupement-bureaux\/#article","isPartOf":{"@id":"https:\/\/vosgesinfo.fr\/epinalinfo\/2016\/11\/primaire-ouverte-de-droite-centre-localisation-regroupement-bureaux\/"},"author":{"name":"C.K.","@id":"https:\/\/vosgesinfo.fr\/epinalinfo\/#\/schema\/person\/6f9a650eeea99d969b6c4ab78fccbe81"},"headline":"Primaire ouverte de la Droite et du Centre &#8211; Localisation et regroupement des bureaux","datePublished":"2016-11-18T12:00:33+00:00","dateModified":"2016-11-18T12:00:33+00:00","mainEntityOfPage":{"@id":"https:\/\/vosgesinfo.fr\/epinalinfo\/2016\/11\/primaire-ouverte-de-droite-centre-localisation-regroupement-bureaux\/"},"wordCount":1121,"commentCount":0,"publisher":{"@id":"https:\/\/vosgesinfo.fr\/epinalinfo\/#organization"},"image":{"@id":"https:\/\/vosgesinfo.fr\/epinalinfo\/2016\/11\/primaire-ouverte-de-droite-centre-localisation-regroupement-bureaux\/#primaryimage"},"thumbnailUrl":"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/3\/2017\/04\/vote.jpg","keywords":["bureaux de vote","Localisation","Primaire ouverte de la Droite et du Centre"],"articleSection":["A la Une","Vosges"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vosgesinfo.fr\/epinalinfo\/2016\/11\/primaire-ouverte-de-droite-centre-localisation-regroupement-bureaux\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vosgesinfo.fr\/epinalinfo\/2016\/11\/primaire-ouverte-de-droite-centre-localisation-regroupement-bureaux\/","url":"https:\/\/vosgesinfo.fr\/epinalinfo\/2016\/11\/primaire-ouverte-de-droite-centre-localisation-regroupement-bureaux\/","name":"Primaire ouverte de la Droite et du Centre - Localisation et regroupement des bureaux - Epinal Info","isPartOf":{"@id":"https:\/\/vosgesinfo.fr\/epinalinfo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vosgesinfo.fr\/epinalinfo\/2016\/11\/primaire-ouverte-de-droite-centre-localisation-regroupement-bureaux\/#primaryimage"},"image":{"@id":"https:\/\/vosgesinfo.fr\/epinalinfo\/2016\/11\/primaire-ouverte-de-droite-centre-localisation-regroupement-bureaux\/#primaryimage"},"thumbnailUrl":"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/3\/2017\/04\/vote.jpg","datePublished":"2016-11-18T12:00:33+00:00","dateModified":"2016-11-18T12:00:33+00:00","breadcrumb":{"@id":"https:\/\/vosgesinfo.fr\/epinalinfo\/2016\/11\/primaire-ouverte-de-droite-centre-localisation-regroupement-bureaux\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vosgesinfo.fr\/epinalinfo\/2016\/11\/primaire-ouverte-de-droite-centre-localisation-regroupement-bureaux\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vosgesinfo.fr\/epinalinfo\/2016\/11\/primaire-ouverte-de-droite-centre-localisation-regroupement-bureaux\/#primaryimage","url":"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/3\/2017\/04\/vote.jpg","contentUrl":"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/3\/2017\/04\/vote.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/vosgesinfo.fr\/epinalinfo\/2016\/11\/primaire-ouverte-de-droite-centre-localisation-regroupement-bureaux\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/vosgesinfo.fr\/epinalinfo\/"},{"@type":"ListItem","position":2,"name":"Primaire ouverte de la Droite et du Centre &#8211; Localisation et regroupement des bureaux"}]},{"@type":"WebSite","@id":"https:\/\/vosgesinfo.fr\/epinalinfo\/#website","url":"https:\/\/vosgesinfo.fr\/epinalinfo\/","name":"Epinal Info","description":"Toute l&#039;actualit\u00e9 d&#039;\u00c9pinal","publisher":{"@id":"https:\/\/vosgesinfo.fr\/epinalinfo\/#organization"},"alternateName":"Toute l'actualit\u00e9 d'\u00c9pinal","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vosgesinfo.fr\/epinalinfo\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/vosgesinfo.fr\/epinalinfo\/#organization","name":"Epinal Info","url":"https:\/\/vosgesinfo.fr\/epinalinfo\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vosgesinfo.fr\/epinalinfo\/#\/schema\/logo\/image\/","url":"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/3\/2023\/08\/logo-epinalinfos.svg","contentUrl":"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/3\/2023\/08\/logo-epinalinfos.svg","width":1,"height":1,"caption":"Epinal Info"},"image":{"@id":"https:\/\/vosgesinfo.fr\/epinalinfo\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Epinalinfos","https:\/\/x.com\/VosgesInfo88","https:\/\/www.youtube.com\/@vosgesinfo"]},{"@type":"Person","@id":"https:\/\/vosgesinfo.fr\/epinalinfo\/#\/schema\/person\/6f9a650eeea99d969b6c4ab78fccbe81","name":"C.K.","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vosgesinfo.fr\/epinalinfo\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/48e3fc7f8421ba8942be6b74a2b7f014ca39bc00dece156b7a8e098ae7dc87bf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/48e3fc7f8421ba8942be6b74a2b7f014ca39bc00dece156b7a8e098ae7dc87bf?s=96&d=mm&r=g","caption":"C.K."},"url":"https:\/\/vosgesinfo.fr\/epinalinfo\/author\/celia-k-n\/"}]}},"_links":{"self":[{"href":"https:\/\/vosgesinfo.fr\/epinalinfo\/wp-json\/wp\/v2\/posts\/67379","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vosgesinfo.fr\/epinalinfo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vosgesinfo.fr\/epinalinfo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vosgesinfo.fr\/epinalinfo\/wp-json\/wp\/v2\/users\/52"}],"replies":[{"embeddable":true,"href":"https:\/\/vosgesinfo.fr\/epinalinfo\/wp-json\/wp\/v2\/comments?post=67379"}],"version-history":[{"count":0,"href":"https:\/\/vosgesinfo.fr\/epinalinfo\/wp-json\/wp\/v2\/posts\/67379\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vosgesinfo.fr\/epinalinfo\/wp-json\/wp\/v2\/media\/12891"}],"wp:attachment":[{"href":"https:\/\/vosgesinfo.fr\/epinalinfo\/wp-json\/wp\/v2\/media?parent=67379"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vosgesinfo.fr\/epinalinfo\/wp-json\/wp\/v2\/categories?post=67379"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vosgesinfo.fr\/epinalinfo\/wp-json\/wp\/v2\/tags?post=67379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}