{"id":27411,"date":"2024-11-22T18:40:14","date_gmt":"2024-11-22T17:40:14","guid":{"rendered":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/2024\/11\/une-centaine-de-poids-lourds-bloques-sur-la-rn57-ce-vendredi-22-novembre\/"},"modified":"2024-11-22T18:40:14","modified_gmt":"2024-11-22T17:40:14","slug":"une-centaine-de-poids-lourds-bloques-sur-la-rn57-ce-vendredi-22-novembre","status":"publish","type":"post","link":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/2024\/11\/une-centaine-de-poids-lourds-bloques-sur-la-rn57-ce-vendredi-22-novembre\/","title":{"rendered":"Une centaine de poids-lourds bloqu\u00e9s sur la RN57 ce vendredi 22 novembre"},"content":{"rendered":"<p><a href=\"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/5\/2024\/11\/blocage-camions-rn57.jpg\"><img decoding=\"async\" class=\"aligncenter size-large wp-image-75748\" src=\"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/5\/2024\/11\/blocage-camions-rn57-1024x768.jpg\" alt=\"\" width=\"1024\" height=\"768\" \/><\/a><\/p>\n<p><strong>Suite \u00e0 la vigilance orange neige et verglas ce vendredi 22 novembre, une d\u00e9cision pr\u00e9fectorale a interdit la circulation des poids-lourds sur la RN 57 jusqu&rsquo;\u00e0 14 h. Ainsi, une op\u00e9ration d&rsquo;immobilisation des camions a \u00e9t\u00e9 men\u00e9e par la police qui invitait les chauffeurs \u00e0 s&rsquo;arr\u00eater sur la voie de droite au niveau de la station Total de Saint-Nabord dans le sens Epinal &gt; Remiremont. La circulation des poids-lourds \u00e9tant importante sur cet axe, une centaine de v\u00e9hicules lourds se sont rapidement retrouv\u00e9s \u00e0 la file sur environ 3 km.<\/strong><\/p>\n<p>Retrouvez notre Reel ici : <a href=\"https:\/\/www.facebook.com\/reel\/526880157002947\" target=\"_blank\" rel=\"noopener\">https:\/\/www.facebook.com\/reel\/526880157002947<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Suite \u00e0 la vigilance orange neige et verglas ce vendredi 22 novembre, une d\u00e9cision pr\u00e9fectorale a interdit la circulation des [&hellip;]<\/p>\n","protected":false},"author":418,"featured_media":27412,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29,7591,383,294,380,381,384],"tags":[7590,1765,1329],"class_list":["post-27411","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-la-une","category-circulation","category-epinal","category-gerardmer","category-la-plaine-des-vosges","category-remiremont","category-saint-die","tag-arrete-prefectoral","tag-poids-lourds","tag-rn57"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Une centaine de poids-lourds bloqu\u00e9s sur la RN57 ce vendredi 22 novembre - La Plaine des Vosges<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/2024\/11\/une-centaine-de-poids-lourds-bloques-sur-la-rn57-ce-vendredi-22-novembre\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Une centaine de poids-lourds bloqu\u00e9s sur la RN57 ce vendredi 22 novembre - La Plaine des Vosges\" \/>\n<meta name=\"twitter:description\" content=\"Suite \u00e0 la vigilance orange neige et verglas ce vendredi 22 novembre, une d\u00e9cision pr\u00e9fectorale a interdit la circulation des [&hellip;]\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/2\/2024\/11\/blocage-camions-rn57.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@VosgesInfo88\" \/>\n<meta name=\"twitter:site\" content=\"@VosgesInfo88\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"C.M\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/2024\/11\/une-centaine-de-poids-lourds-bloques-sur-la-rn57-ce-vendredi-22-novembre\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/2024\/11\/une-centaine-de-poids-lourds-bloques-sur-la-rn57-ce-vendredi-22-novembre\/\"},\"author\":{\"name\":\"C.M\",\"@id\":\"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/#\/schema\/person\/4f38cd3068e342935b7304695c797d08\"},\"headline\":\"Une centaine de poids-lourds bloqu\u00e9s sur la RN57 ce vendredi 22 novembre\",\"datePublished\":\"2024-11-22T17:40:14+00:00\",\"dateModified\":\"2024-11-22T17:40:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/2024\/11\/une-centaine-de-poids-lourds-bloques-sur-la-rn57-ce-vendredi-22-novembre\/\"},\"wordCount\":114,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/#organization\"},\"image\":{\"@id\":\"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/2024\/11\/une-centaine-de-poids-lourds-bloques-sur-la-rn57-ce-vendredi-22-novembre\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/2\/2024\/11\/blocage-camions-rn57.jpg\",\"keywords\":[\"Arr\u00eat\u00e9 pr\u00e9fectoral\",\"poids lourds\",\"RN57\"],\"articleSection\":[\"A la Une\",\"Circulation\",\"Epinal\",\"G\u00e9rardmer\",\"La plaine des vosges\",\"Remiremont\",\"Saint-di\u00e9\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/2024\/11\/une-centaine-de-poids-lourds-bloques-sur-la-rn57-ce-vendredi-22-novembre\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/2024\/11\/une-centaine-de-poids-lourds-bloques-sur-la-rn57-ce-vendredi-22-novembre\/\",\"url\":\"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/2024\/11\/une-centaine-de-poids-lourds-bloques-sur-la-rn57-ce-vendredi-22-novembre\/\",\"name\":\"Une centaine de poids-lourds bloqu\u00e9s sur la RN57 ce vendredi 22 novembre - La Plaine des Vosges\",\"isPartOf\":{\"@id\":\"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/2024\/11\/une-centaine-de-poids-lourds-bloques-sur-la-rn57-ce-vendredi-22-novembre\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/2024\/11\/une-centaine-de-poids-lourds-bloques-sur-la-rn57-ce-vendredi-22-novembre\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/2\/2024\/11\/blocage-camions-rn57.jpg\",\"datePublished\":\"2024-11-22T17:40:14+00:00\",\"dateModified\":\"2024-11-22T17:40:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/2024\/11\/une-centaine-de-poids-lourds-bloques-sur-la-rn57-ce-vendredi-22-novembre\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/2024\/11\/une-centaine-de-poids-lourds-bloques-sur-la-rn57-ce-vendredi-22-novembre\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/2024\/11\/une-centaine-de-poids-lourds-bloques-sur-la-rn57-ce-vendredi-22-novembre\/#primaryimage\",\"url\":\"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/2\/2024\/11\/blocage-camions-rn57.jpg\",\"contentUrl\":\"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/2\/2024\/11\/blocage-camions-rn57.jpg\",\"width\":1170,\"height\":877},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/2024\/11\/une-centaine-de-poids-lourds-bloques-sur-la-rn57-ce-vendredi-22-novembre\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Une centaine de poids-lourds bloqu\u00e9s sur la RN57 ce vendredi 22 novembre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/#website\",\"url\":\"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/\",\"name\":\"La Plaine des Vosges\",\"description\":\"Toute l&#039;actualit\u00e9 de la plaine de Vosges\",\"publisher\":{\"@id\":\"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/#organization\"},\"alternateName\":\"Toute l'actualit\u00e9 de la plaine des Vosges\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/#organization\",\"name\":\"La Plaine des Vosges\",\"url\":\"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/2\/2023\/08\/logo-laplaineinfo.svg\",\"contentUrl\":\"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/2\/2023\/08\/logo-laplaineinfo.svg\",\"width\":1,\"height\":1,\"caption\":\"La Plaine des Vosges\"},\"image\":{\"@id\":\"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/laplainedesvosges\",\"https:\/\/x.com\/VosgesInfo88\",\"https:\/\/www.youtube.com\/@vosgesinfo\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/#\/schema\/person\/4f38cd3068e342935b7304695c797d08\",\"name\":\"C.M\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/fe9daaef0164d920717484172682f3c5c9bcf7d42aa8c7048c76c34f0eb6c8da?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/fe9daaef0164d920717484172682f3c5c9bcf7d42aa8c7048c76c34f0eb6c8da?s=96&d=mm&r=g\",\"caption\":\"C.M\"},\"url\":\"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/author\/cm88200\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Une centaine de poids-lourds bloqu\u00e9s sur la RN57 ce vendredi 22 novembre - La Plaine des Vosges","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/2024\/11\/une-centaine-de-poids-lourds-bloques-sur-la-rn57-ce-vendredi-22-novembre\/","twitter_card":"summary_large_image","twitter_title":"Une centaine de poids-lourds bloqu\u00e9s sur la RN57 ce vendredi 22 novembre - La Plaine des Vosges","twitter_description":"Suite \u00e0 la vigilance orange neige et verglas ce vendredi 22 novembre, une d\u00e9cision pr\u00e9fectorale a interdit la circulation des [&hellip;]","twitter_image":"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/2\/2024\/11\/blocage-camions-rn57.jpg","twitter_creator":"@VosgesInfo88","twitter_site":"@VosgesInfo88","twitter_misc":{"\u00c9crit par":"C.M","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/2024\/11\/une-centaine-de-poids-lourds-bloques-sur-la-rn57-ce-vendredi-22-novembre\/#article","isPartOf":{"@id":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/2024\/11\/une-centaine-de-poids-lourds-bloques-sur-la-rn57-ce-vendredi-22-novembre\/"},"author":{"name":"C.M","@id":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/#\/schema\/person\/4f38cd3068e342935b7304695c797d08"},"headline":"Une centaine de poids-lourds bloqu\u00e9s sur la RN57 ce vendredi 22 novembre","datePublished":"2024-11-22T17:40:14+00:00","dateModified":"2024-11-22T17:40:14+00:00","mainEntityOfPage":{"@id":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/2024\/11\/une-centaine-de-poids-lourds-bloques-sur-la-rn57-ce-vendredi-22-novembre\/"},"wordCount":114,"commentCount":0,"publisher":{"@id":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/#organization"},"image":{"@id":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/2024\/11\/une-centaine-de-poids-lourds-bloques-sur-la-rn57-ce-vendredi-22-novembre\/#primaryimage"},"thumbnailUrl":"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/2\/2024\/11\/blocage-camions-rn57.jpg","keywords":["Arr\u00eat\u00e9 pr\u00e9fectoral","poids lourds","RN57"],"articleSection":["A la Une","Circulation","Epinal","G\u00e9rardmer","La plaine des vosges","Remiremont","Saint-di\u00e9"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/2024\/11\/une-centaine-de-poids-lourds-bloques-sur-la-rn57-ce-vendredi-22-novembre\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/2024\/11\/une-centaine-de-poids-lourds-bloques-sur-la-rn57-ce-vendredi-22-novembre\/","url":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/2024\/11\/une-centaine-de-poids-lourds-bloques-sur-la-rn57-ce-vendredi-22-novembre\/","name":"Une centaine de poids-lourds bloqu\u00e9s sur la RN57 ce vendredi 22 novembre - La Plaine des Vosges","isPartOf":{"@id":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/2024\/11\/une-centaine-de-poids-lourds-bloques-sur-la-rn57-ce-vendredi-22-novembre\/#primaryimage"},"image":{"@id":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/2024\/11\/une-centaine-de-poids-lourds-bloques-sur-la-rn57-ce-vendredi-22-novembre\/#primaryimage"},"thumbnailUrl":"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/2\/2024\/11\/blocage-camions-rn57.jpg","datePublished":"2024-11-22T17:40:14+00:00","dateModified":"2024-11-22T17:40:14+00:00","breadcrumb":{"@id":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/2024\/11\/une-centaine-de-poids-lourds-bloques-sur-la-rn57-ce-vendredi-22-novembre\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/2024\/11\/une-centaine-de-poids-lourds-bloques-sur-la-rn57-ce-vendredi-22-novembre\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/2024\/11\/une-centaine-de-poids-lourds-bloques-sur-la-rn57-ce-vendredi-22-novembre\/#primaryimage","url":"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/2\/2024\/11\/blocage-camions-rn57.jpg","contentUrl":"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/2\/2024\/11\/blocage-camions-rn57.jpg","width":1170,"height":877},{"@type":"BreadcrumbList","@id":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/2024\/11\/une-centaine-de-poids-lourds-bloques-sur-la-rn57-ce-vendredi-22-novembre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/"},{"@type":"ListItem","position":2,"name":"Une centaine de poids-lourds bloqu\u00e9s sur la RN57 ce vendredi 22 novembre"}]},{"@type":"WebSite","@id":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/#website","url":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/","name":"La Plaine des Vosges","description":"Toute l&#039;actualit\u00e9 de la plaine de Vosges","publisher":{"@id":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/#organization"},"alternateName":"Toute l'actualit\u00e9 de la plaine des Vosges","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/#organization","name":"La Plaine des Vosges","url":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/#\/schema\/logo\/image\/","url":"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/2\/2023\/08\/logo-laplaineinfo.svg","contentUrl":"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/2\/2023\/08\/logo-laplaineinfo.svg","width":1,"height":1,"caption":"La Plaine des Vosges"},"image":{"@id":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/laplainedesvosges","https:\/\/x.com\/VosgesInfo88","https:\/\/www.youtube.com\/@vosgesinfo"]},{"@type":"Person","@id":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/#\/schema\/person\/4f38cd3068e342935b7304695c797d08","name":"C.M","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/fe9daaef0164d920717484172682f3c5c9bcf7d42aa8c7048c76c34f0eb6c8da?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fe9daaef0164d920717484172682f3c5c9bcf7d42aa8c7048c76c34f0eb6c8da?s=96&d=mm&r=g","caption":"C.M"},"url":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/author\/cm88200\/"}]}},"_links":{"self":[{"href":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/wp-json\/wp\/v2\/posts\/27411","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/wp-json\/wp\/v2\/users\/418"}],"replies":[{"embeddable":true,"href":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/wp-json\/wp\/v2\/comments?post=27411"}],"version-history":[{"count":0,"href":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/wp-json\/wp\/v2\/posts\/27411\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/wp-json\/wp\/v2\/media\/27412"}],"wp:attachment":[{"href":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/wp-json\/wp\/v2\/media?parent=27411"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/wp-json\/wp\/v2\/categories?post=27411"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/wp-json\/wp\/v2\/tags?post=27411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}