{"id":29795,"date":"2025-04-28T11:00:25","date_gmt":"2025-04-28T09:00:25","guid":{"rendered":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/?p=29795"},"modified":"2025-04-28T11:00:25","modified_gmt":"2025-04-28T09:00:25","slug":"de-nombreux-complements-alimentaires-rappeles-en-raison-de-risques-graves-pour-la-sante","status":"publish","type":"post","link":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/2025\/04\/de-nombreux-complements-alimentaires-rappeles-en-raison-de-risques-graves-pour-la-sante\/","title":{"rendered":"De nombreux compl\u00e9ments alimentaires rappel\u00e9s en raison de risques graves pour la sant\u00e9"},"content":{"rendered":"<div id=\"attachment_81254\" style=\"width: 2010px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/5\/2025\/04\/complements-alimentaires.jpg\"><img decoding=\"async\" aria-describedby=\"caption-attachment-81254\" class=\"size-full wp-image-81254\" src=\"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/5\/2025\/04\/complements-alimentaires.jpg\" alt=\"\" width=\"2000\" height=\"1333\" \/><\/a><p id=\"caption-attachment-81254\" class=\"wp-caption-text\">Photographie d&rsquo;illustration.<\/p><\/div>\n<p class=\"\" data-start=\"119\" data-end=\"399\"><strong>Un nombre important de compl\u00e9ments alimentaires est actuellement rappel\u00e9 en France, selon le site gouvernemental Rappel Conso. Sont concern\u00e9s des produits de type coupe-faim ou br\u00fble-graisse contenant du Garcinia cambogia, \u00e9galement connu sous le nom de tamarinier de Malabar.<\/strong><\/p>\n<p class=\"\" data-start=\"401\" data-end=\"1175\">La consommation d&rsquo;extraits de cette plante a \u00e9t\u00e9 associ\u00e9e \u00e0 de nombreux effets ind\u00e9sirables graves. D&rsquo;apr\u00e8s l&rsquo;association UFC-Que Choisir, des troubles psychiatriques, digestifs, cardiaques et musculaires ont \u00e9t\u00e9 signal\u00e9s, ainsi que des atteintes h\u00e9patiques, dont une ayant entra\u00een\u00e9 un d\u00e9c\u00e8s. Face \u00e0 ce constat alarmant, l&rsquo;Anses (Agence nationale de s\u00e9curit\u00e9 sanitaire de l&rsquo;alimentation, de l&rsquo;environnement et du travail) d\u00e9conseille fortement la consommation de compl\u00e9ments alimentaires \u00e0 base de <strong data-start=\"899\" data-end=\"920\">Garcinia cambogia<\/strong>. Elle rappelle \u00e9galement que les all\u00e9gations concernant la perte de poids ou la r\u00e9gulation de la glyc\u00e9mie et du cholest\u00e9rol n&rsquo;ont jamais \u00e9t\u00e9 valid\u00e9es scientifiquement. Les risques pour la sant\u00e9 sont donc jug\u00e9s bien sup\u00e9rieurs \u00e0 des b\u00e9n\u00e9fices non prouv\u00e9s.<\/p>\n<p class=\"\" data-start=\"1177\" data-end=\"1463\">En r\u00e9action, un arr\u00eat\u00e9 dat\u00e9 du 15 avril 2025 a \u00e9t\u00e9 pris, suspendant pour un an l\u2019importation, l\u2019introduction, ainsi que la mise sur le march\u00e9, \u00e0 titre gratuit ou on\u00e9reux, de tous les compl\u00e9ments alimentaires contenant du <strong data-start=\"1398\" data-end=\"1419\">Garcinia cambogia<\/strong> ou des pr\u00e9parations issues de cette plante.<\/p>\n<p class=\"\" data-start=\"1465\" data-end=\"1677\">Les consommateurs sont invit\u00e9s \u00e0 consulter la liste compl\u00e8te des produits concern\u00e9s sur le site officiel <strong data-start=\"1570\" data-end=\"1586\">Rappel Conso<\/strong> \u00e0 l&rsquo;adresse suivante : <a class=\"\" href=\"https:\/\/rappel.conso.gouv.fr\/categorie\/0\/1\" target=\"_new\" rel=\"noopener\" data-start=\"1610\" data-end=\"1676\">rappel.conso.gouv.fr<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un nombre important de compl\u00e9ments alimentaires est actuellement rappel\u00e9 en France, selon le site gouvernemental Rappel Conso. Sont concern\u00e9s des [&hellip;]<\/p>\n","protected":false},"author":418,"featured_media":29796,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29,383,294,380,381,384,12,18],"tags":[8420,8421,7700],"class_list":["post-29795","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-la-une","category-epinal","category-gerardmer","category-la-plaine-des-vosges","category-remiremont","category-saint-die","category-sante","category-vosges","tag-complements-alimentaires","tag-garcinia-cambogia","tag-rappel-conso"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>De nombreux compl\u00e9ments alimentaires rappel\u00e9s en raison de risques graves pour la sant\u00e9 - La Plaine des Vosges<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/2025\/04\/de-nombreux-complements-alimentaires-rappeles-en-raison-de-risques-graves-pour-la-sante\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"De nombreux compl\u00e9ments alimentaires rappel\u00e9s en raison de risques graves pour la sant\u00e9 - La Plaine des Vosges\" \/>\n<meta name=\"twitter:description\" content=\"Un nombre important de compl\u00e9ments alimentaires est actuellement rappel\u00e9 en France, selon le site gouvernemental Rappel Conso. Sont concern\u00e9s des [&hellip;]\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/2\/2025\/04\/complements-alimentaires.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@VosgesInfo88\" \/>\n<meta name=\"twitter:site\" content=\"@VosgesInfo88\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"C.M\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/2025\/04\/de-nombreux-complements-alimentaires-rappeles-en-raison-de-risques-graves-pour-la-sante\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/2025\/04\/de-nombreux-complements-alimentaires-rappeles-en-raison-de-risques-graves-pour-la-sante\/\"},\"author\":{\"name\":\"C.M\",\"@id\":\"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/#\/schema\/person\/4f38cd3068e342935b7304695c797d08\"},\"headline\":\"De nombreux compl\u00e9ments alimentaires rappel\u00e9s en raison de risques graves pour la sant\u00e9\",\"datePublished\":\"2025-04-28T09:00:25+00:00\",\"dateModified\":\"2025-04-28T09:00:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/2025\/04\/de-nombreux-complements-alimentaires-rappeles-en-raison-de-risques-graves-pour-la-sante\/\"},\"wordCount\":278,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/#organization\"},\"image\":{\"@id\":\"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/2025\/04\/de-nombreux-complements-alimentaires-rappeles-en-raison-de-risques-graves-pour-la-sante\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/2\/2025\/04\/complements-alimentaires.jpg\",\"keywords\":[\"Compl\u00e9ments alimentaires\",\"Garcinia Cambogia\",\"Rappel Conso\"],\"articleSection\":[\"A la Une\",\"Epinal\",\"G\u00e9rardmer\",\"La plaine des vosges\",\"Remiremont\",\"Saint-di\u00e9\",\"Sant\u00e9\",\"Vosges\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/2025\/04\/de-nombreux-complements-alimentaires-rappeles-en-raison-de-risques-graves-pour-la-sante\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/2025\/04\/de-nombreux-complements-alimentaires-rappeles-en-raison-de-risques-graves-pour-la-sante\/\",\"url\":\"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/2025\/04\/de-nombreux-complements-alimentaires-rappeles-en-raison-de-risques-graves-pour-la-sante\/\",\"name\":\"De nombreux compl\u00e9ments alimentaires rappel\u00e9s en raison de risques graves pour la sant\u00e9 - La Plaine des Vosges\",\"isPartOf\":{\"@id\":\"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/2025\/04\/de-nombreux-complements-alimentaires-rappeles-en-raison-de-risques-graves-pour-la-sante\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/2025\/04\/de-nombreux-complements-alimentaires-rappeles-en-raison-de-risques-graves-pour-la-sante\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/2\/2025\/04\/complements-alimentaires.jpg\",\"datePublished\":\"2025-04-28T09:00:25+00:00\",\"dateModified\":\"2025-04-28T09:00:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/2025\/04\/de-nombreux-complements-alimentaires-rappeles-en-raison-de-risques-graves-pour-la-sante\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/2025\/04\/de-nombreux-complements-alimentaires-rappeles-en-raison-de-risques-graves-pour-la-sante\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/2025\/04\/de-nombreux-complements-alimentaires-rappeles-en-raison-de-risques-graves-pour-la-sante\/#primaryimage\",\"url\":\"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/2\/2025\/04\/complements-alimentaires.jpg\",\"contentUrl\":\"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/2\/2025\/04\/complements-alimentaires.jpg\",\"width\":2000,\"height\":1333},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/2025\/04\/de-nombreux-complements-alimentaires-rappeles-en-raison-de-risques-graves-pour-la-sante\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"De nombreux compl\u00e9ments alimentaires rappel\u00e9s en raison de risques graves pour la sant\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/#website\",\"url\":\"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/\",\"name\":\"La Plaine des Vosges\",\"description\":\"Toute l&#039;actualit\u00e9 de la plaine de Vosges\",\"publisher\":{\"@id\":\"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/#organization\"},\"alternateName\":\"Toute l'actualit\u00e9 de la plaine des Vosges\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/#organization\",\"name\":\"La Plaine des Vosges\",\"url\":\"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/2\/2023\/08\/logo-laplaineinfo.svg\",\"contentUrl\":\"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/2\/2023\/08\/logo-laplaineinfo.svg\",\"width\":1,\"height\":1,\"caption\":\"La Plaine des Vosges\"},\"image\":{\"@id\":\"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/laplainedesvosges\",\"https:\/\/x.com\/VosgesInfo88\",\"https:\/\/www.youtube.com\/@vosgesinfo\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/#\/schema\/person\/4f38cd3068e342935b7304695c797d08\",\"name\":\"C.M\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/fe9daaef0164d920717484172682f3c5c9bcf7d42aa8c7048c76c34f0eb6c8da?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/fe9daaef0164d920717484172682f3c5c9bcf7d42aa8c7048c76c34f0eb6c8da?s=96&d=mm&r=g\",\"caption\":\"C.M\"},\"url\":\"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/author\/cm88200\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"De nombreux compl\u00e9ments alimentaires rappel\u00e9s en raison de risques graves pour la sant\u00e9 - La Plaine des Vosges","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/2025\/04\/de-nombreux-complements-alimentaires-rappeles-en-raison-de-risques-graves-pour-la-sante\/","twitter_card":"summary_large_image","twitter_title":"De nombreux compl\u00e9ments alimentaires rappel\u00e9s en raison de risques graves pour la sant\u00e9 - La Plaine des Vosges","twitter_description":"Un nombre important de compl\u00e9ments alimentaires est actuellement rappel\u00e9 en France, selon le site gouvernemental Rappel Conso. Sont concern\u00e9s des [&hellip;]","twitter_image":"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/2\/2025\/04\/complements-alimentaires.jpg","twitter_creator":"@VosgesInfo88","twitter_site":"@VosgesInfo88","twitter_misc":{"\u00c9crit par":"C.M","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/2025\/04\/de-nombreux-complements-alimentaires-rappeles-en-raison-de-risques-graves-pour-la-sante\/#article","isPartOf":{"@id":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/2025\/04\/de-nombreux-complements-alimentaires-rappeles-en-raison-de-risques-graves-pour-la-sante\/"},"author":{"name":"C.M","@id":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/#\/schema\/person\/4f38cd3068e342935b7304695c797d08"},"headline":"De nombreux compl\u00e9ments alimentaires rappel\u00e9s en raison de risques graves pour la sant\u00e9","datePublished":"2025-04-28T09:00:25+00:00","dateModified":"2025-04-28T09:00:25+00:00","mainEntityOfPage":{"@id":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/2025\/04\/de-nombreux-complements-alimentaires-rappeles-en-raison-de-risques-graves-pour-la-sante\/"},"wordCount":278,"commentCount":0,"publisher":{"@id":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/#organization"},"image":{"@id":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/2025\/04\/de-nombreux-complements-alimentaires-rappeles-en-raison-de-risques-graves-pour-la-sante\/#primaryimage"},"thumbnailUrl":"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/2\/2025\/04\/complements-alimentaires.jpg","keywords":["Compl\u00e9ments alimentaires","Garcinia Cambogia","Rappel Conso"],"articleSection":["A la Une","Epinal","G\u00e9rardmer","La plaine des vosges","Remiremont","Saint-di\u00e9","Sant\u00e9","Vosges"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/2025\/04\/de-nombreux-complements-alimentaires-rappeles-en-raison-de-risques-graves-pour-la-sante\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/2025\/04\/de-nombreux-complements-alimentaires-rappeles-en-raison-de-risques-graves-pour-la-sante\/","url":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/2025\/04\/de-nombreux-complements-alimentaires-rappeles-en-raison-de-risques-graves-pour-la-sante\/","name":"De nombreux compl\u00e9ments alimentaires rappel\u00e9s en raison de risques graves pour la sant\u00e9 - La Plaine des Vosges","isPartOf":{"@id":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/2025\/04\/de-nombreux-complements-alimentaires-rappeles-en-raison-de-risques-graves-pour-la-sante\/#primaryimage"},"image":{"@id":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/2025\/04\/de-nombreux-complements-alimentaires-rappeles-en-raison-de-risques-graves-pour-la-sante\/#primaryimage"},"thumbnailUrl":"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/2\/2025\/04\/complements-alimentaires.jpg","datePublished":"2025-04-28T09:00:25+00:00","dateModified":"2025-04-28T09:00:25+00:00","breadcrumb":{"@id":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/2025\/04\/de-nombreux-complements-alimentaires-rappeles-en-raison-de-risques-graves-pour-la-sante\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/2025\/04\/de-nombreux-complements-alimentaires-rappeles-en-raison-de-risques-graves-pour-la-sante\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/2025\/04\/de-nombreux-complements-alimentaires-rappeles-en-raison-de-risques-graves-pour-la-sante\/#primaryimage","url":"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/2\/2025\/04\/complements-alimentaires.jpg","contentUrl":"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/2\/2025\/04\/complements-alimentaires.jpg","width":2000,"height":1333},{"@type":"BreadcrumbList","@id":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/2025\/04\/de-nombreux-complements-alimentaires-rappeles-en-raison-de-risques-graves-pour-la-sante\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/"},{"@type":"ListItem","position":2,"name":"De nombreux compl\u00e9ments alimentaires rappel\u00e9s en raison de risques graves pour la sant\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/#website","url":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/","name":"La Plaine des Vosges","description":"Toute l&#039;actualit\u00e9 de la plaine de Vosges","publisher":{"@id":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/#organization"},"alternateName":"Toute l'actualit\u00e9 de la plaine des Vosges","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/#organization","name":"La Plaine des Vosges","url":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/#\/schema\/logo\/image\/","url":"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/2\/2023\/08\/logo-laplaineinfo.svg","contentUrl":"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/2\/2023\/08\/logo-laplaineinfo.svg","width":1,"height":1,"caption":"La Plaine des Vosges"},"image":{"@id":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/laplainedesvosges","https:\/\/x.com\/VosgesInfo88","https:\/\/www.youtube.com\/@vosgesinfo"]},{"@type":"Person","@id":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/#\/schema\/person\/4f38cd3068e342935b7304695c797d08","name":"C.M","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/fe9daaef0164d920717484172682f3c5c9bcf7d42aa8c7048c76c34f0eb6c8da?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fe9daaef0164d920717484172682f3c5c9bcf7d42aa8c7048c76c34f0eb6c8da?s=96&d=mm&r=g","caption":"C.M"},"url":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/author\/cm88200\/"}]}},"_links":{"self":[{"href":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/wp-json\/wp\/v2\/posts\/29795","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/wp-json\/wp\/v2\/users\/418"}],"replies":[{"embeddable":true,"href":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/wp-json\/wp\/v2\/comments?post=29795"}],"version-history":[{"count":0,"href":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/wp-json\/wp\/v2\/posts\/29795\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/wp-json\/wp\/v2\/media\/29796"}],"wp:attachment":[{"href":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/wp-json\/wp\/v2\/media?parent=29795"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/wp-json\/wp\/v2\/categories?post=29795"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vosgesinfo.fr\/laplainedesvosgesinfo\/wp-json\/wp\/v2\/tags?post=29795"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}