{"id":43938,"date":"2021-07-26T04:59:52","date_gmt":"2021-07-26T02:59:52","guid":{"rendered":"https:\/\/vosgesinfo.fr\/remiremontinfo\/2021\/07\/saint-nabord-inauguration-nouveaux-equipements-sportifs-site-perrey-de-larboretum\/"},"modified":"2021-07-26T04:59:52","modified_gmt":"2021-07-26T02:59:52","slug":"saint-nabord-inauguration-nouveaux-equipements-sportifs-site-perrey-de-larboretum","status":"publish","type":"post","link":"https:\/\/vosgesinfo.fr\/remiremontinfo\/2021\/07\/saint-nabord-inauguration-nouveaux-equipements-sportifs-site-perrey-de-larboretum\/","title":{"rendered":"Saint-Nabord\u00a0: inauguration des nouveaux \u00e9quipements sportifs sur le site des Perrey et de l&rsquo;Arboretum"},"content":{"rendered":"<p style=\"text-align: center;\"><a href=\"\/2021\/07\/224093818_381239876858402_7119046583882812857_n1.jpg\"><img decoding=\"async\" class=\"alignnone size-full wp-image-322796\" src=\"\/2021\/07\/224093818_381239876858402_7119046583882812857_n1.jpg\" alt=\"224093818_381239876858402_7119046583882812857_n\" width=\"800\" height=\"625\" \/><\/a><\/p>\n<h2><span style=\"font-size: 12pt;\"><strong>Une fen\u00eatre de ciel bleu s\u2019est ouverte ce samedi matin, au-dessus de Saint-Nabord pour l\u2019inauguration des nouveaux \u00e9quipements sportifs fra\u00eechement install\u00e9s sur le site des Perrey, et la pr\u00e9sentation du r\u00e9am\u00e9nagement de l\u2019arboretum.<\/strong><\/span><\/h2>\n<p>Jean Hingray, S\u00e9nateur des Vosges, Christophe Naegelen, D\u00e9put\u00e9 et Conseiller r\u00e9gional, Fran\u00e7ois Vnnson, Pr\u00e9sident du Conseil d\u00e9partemental, les \u00e9lus de la commune, tous ont r\u00e9pondu \u00e0 l\u2019invitation de notre Maire, Jean-Pierre Calmels et de Julien Balland, Adjoint aux Sports et aux Associations, initiateur de ces beaux projets, pour fouler de leurs pieds le nouveau parcours running de 1,3 km dessin\u00e9 en p\u00e9riph\u00e9rie du stade et \u00e9prouver leur force musculaire sur les agr\u00e8s de la plateforme fitness.<\/p>\n<p>Contrainte par la situation sanitaire \u00e0 un accueil limit\u00e9 du public, la municipalit\u00e9 a n\u00e9anmoins convi\u00e9, \u00e0 cet \u00e9v\u00e9nement, les associations Falli\u00e8res Sport D\u00e9tente et Le Slec, l\u2019une et l\u2019autre, fortement investies dans l\u2019am\u00e9nagement des nouveaux parcours VTT et sentiers de randonn\u00e9es. Le c\u00e9l\u00e8bre sportif vosgien, St\u00e9phane Brognart, ultra trailer, adepte des d\u00e9fis les plus fous comme la travers\u00e9e de l\u2019Atlantique \u00e0 la rame en solitaire, nous a fait \u00e9galement l\u2019honneur d\u2019illuminer cette matin\u00e9e de sa belle pr\u00e9sence.<\/p>\n<p>Le programme de la journ\u00e9e s\u2019est poursuivi, pour les plus courageux, par une randonn\u00e9e en VTT au d\u00e9part des Perrey pour \u00e9trenner les nouveaux circuits r\u00e9cemment balis\u00e9s. Cette joyeuse \u00e9quip\u00e9e a rejoint C\u00e9dric babel, Adjoint \u00e0 la For\u00eat et les membres de l\u2019ONF, Patrick Kubler, directeur de l\u2019agence Vosges Montagne et Gilles Oudot, Responsable de l\u2019unit\u00e9 territoriale de Remiremont, pour c\u00e9l\u00e9brer \u00e0 l\u2019ombre des belles futaies le r\u00e9am\u00e9nagement de l\u2019arboretum r\u00e9alis\u00e9 en collaboration avec Philippe Michel, agent technique de l\u2019ONF en charge du domaine communal forestier de Saint-Nabord. Apr\u00e8s les discours de circonstance, les visiteurs ont sillonn\u00e9 le site \u00e0 la d\u00e9couverte des belles vari\u00e9t\u00e9s de r\u00e9sineux et feuillus introduites \u00e0 sa cr\u00e9ation en 2000.<\/p>\n<p>Lors de son allocution, Fran\u00e7ois Vannson, rappelant \u00e0 son auditoire avoir inaugur\u00e9 ce m\u00eame arboretum 20 ans plus t\u00f4t, a notamment pr\u00e9cis\u00e9 qu\u2019il \u00e9tait, \u00e0 cette occasion, devenu le parrain de l\u2019\u00e9pic\u00e9a de Sitka. Arbre qu\u2019il a eu le bonheur de retrouver durant la visite, sain et vigoureux, parmi les quelque 40 esp\u00e8ces pr\u00e9sentes dans ce laboratoire exp\u00e9rimental et qui n\u2019ont malheureusement pas toutes r\u00e9sist\u00e9 aux grosses chaleurs et changements climatiques.<\/p>\n<p><em>Source\u00a0: Mairie de Saint-Nabord<\/em><\/p>\n\n","protected":false},"excerpt":{"rendered":"<p>Une fen\u00eatre de ciel bleu s\u2019est ouverte ce samedi matin, au-dessus de Saint-Nabord pour l\u2019inauguration des nouveaux \u00e9quipements sportifs fra\u00eechement [&hellip;]<\/p>\n","protected":false},"author":407,"featured_media":43939,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26,35,100],"tags":[],"class_list":["post-43938","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-la-une","category-remiremont-son-canton","category-saint-nabord"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Saint-Nabord\u00a0: inauguration des nouveaux \u00e9quipements sportifs sur le site des Perrey et de l&#039;Arboretum - Remiremont Info<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vosgesinfo.fr\/remiremontinfo\/2021\/07\/saint-nabord-inauguration-nouveaux-equipements-sportifs-site-perrey-de-larboretum\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Saint-Nabord\u00a0: inauguration des nouveaux \u00e9quipements sportifs sur le site des Perrey et de l&#039;Arboretum - Remiremont Info\" \/>\n<meta name=\"twitter:description\" content=\"Une fen\u00eatre de ciel bleu s\u2019est ouverte ce samedi matin, au-dessus de Saint-Nabord pour l\u2019inauguration des nouveaux \u00e9quipements sportifs fra\u00eechement [&hellip;]\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/5\/2024\/09\/202107224093818-381239876858402-7119046583882812857-n1.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@VosgesInfo88\" \/>\n<meta name=\"twitter:site\" content=\"@VosgesInfo88\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"C D\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/vosgesinfo.fr\/remiremontinfo\/2021\/07\/saint-nabord-inauguration-nouveaux-equipements-sportifs-site-perrey-de-larboretum\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/vosgesinfo.fr\/remiremontinfo\/2021\/07\/saint-nabord-inauguration-nouveaux-equipements-sportifs-site-perrey-de-larboretum\/\"},\"author\":{\"name\":\"C D\",\"@id\":\"https:\/\/vosgesinfo.fr\/remiremontinfo\/#\/schema\/person\/3bfd164d5218a185b1db68655a265316\"},\"headline\":\"Saint-Nabord\u00a0: inauguration des nouveaux \u00e9quipements sportifs sur le site des Perrey et de l&rsquo;Arboretum\",\"datePublished\":\"2021-07-26T02:59:52+00:00\",\"dateModified\":\"2021-07-26T02:59:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/vosgesinfo.fr\/remiremontinfo\/2021\/07\/saint-nabord-inauguration-nouveaux-equipements-sportifs-site-perrey-de-larboretum\/\"},\"wordCount\":464,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/vosgesinfo.fr\/remiremontinfo\/#organization\"},\"image\":{\"@id\":\"https:\/\/vosgesinfo.fr\/remiremontinfo\/2021\/07\/saint-nabord-inauguration-nouveaux-equipements-sportifs-site-perrey-de-larboretum\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/5\/2024\/09\/202107224093818-381239876858402-7119046583882812857-n1.jpg\",\"articleSection\":[\"A la Une\",\"Remiremont &amp; son canton\",\"Saint-Nabord\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/vosgesinfo.fr\/remiremontinfo\/2021\/07\/saint-nabord-inauguration-nouveaux-equipements-sportifs-site-perrey-de-larboretum\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/vosgesinfo.fr\/remiremontinfo\/2021\/07\/saint-nabord-inauguration-nouveaux-equipements-sportifs-site-perrey-de-larboretum\/\",\"url\":\"https:\/\/vosgesinfo.fr\/remiremontinfo\/2021\/07\/saint-nabord-inauguration-nouveaux-equipements-sportifs-site-perrey-de-larboretum\/\",\"name\":\"Saint-Nabord\u00a0: inauguration des nouveaux \u00e9quipements sportifs sur le site des Perrey et de l'Arboretum - Remiremont Info\",\"isPartOf\":{\"@id\":\"https:\/\/vosgesinfo.fr\/remiremontinfo\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/vosgesinfo.fr\/remiremontinfo\/2021\/07\/saint-nabord-inauguration-nouveaux-equipements-sportifs-site-perrey-de-larboretum\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/vosgesinfo.fr\/remiremontinfo\/2021\/07\/saint-nabord-inauguration-nouveaux-equipements-sportifs-site-perrey-de-larboretum\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/5\/2024\/09\/202107224093818-381239876858402-7119046583882812857-n1.jpg\",\"datePublished\":\"2021-07-26T02:59:52+00:00\",\"dateModified\":\"2021-07-26T02:59:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/vosgesinfo.fr\/remiremontinfo\/2021\/07\/saint-nabord-inauguration-nouveaux-equipements-sportifs-site-perrey-de-larboretum\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/vosgesinfo.fr\/remiremontinfo\/2021\/07\/saint-nabord-inauguration-nouveaux-equipements-sportifs-site-perrey-de-larboretum\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/vosgesinfo.fr\/remiremontinfo\/2021\/07\/saint-nabord-inauguration-nouveaux-equipements-sportifs-site-perrey-de-larboretum\/#primaryimage\",\"url\":\"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/5\/2024\/09\/202107224093818-381239876858402-7119046583882812857-n1.jpg\",\"contentUrl\":\"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/5\/2024\/09\/202107224093818-381239876858402-7119046583882812857-n1.jpg\",\"width\":800,\"height\":625},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/vosgesinfo.fr\/remiremontinfo\/2021\/07\/saint-nabord-inauguration-nouveaux-equipements-sportifs-site-perrey-de-larboretum\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/vosgesinfo.fr\/remiremontinfo\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Saint-Nabord\u00a0: inauguration des nouveaux \u00e9quipements sportifs sur le site des Perrey et de l&rsquo;Arboretum\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/vosgesinfo.fr\/remiremontinfo\/#website\",\"url\":\"https:\/\/vosgesinfo.fr\/remiremontinfo\/\",\"name\":\"Remiremont Info\",\"description\":\"Toute l&#039;actualit\u00e9 de Remiremont\",\"publisher\":{\"@id\":\"https:\/\/vosgesinfo.fr\/remiremontinfo\/#organization\"},\"alternateName\":\"Toute l'actualit\u00e9 de Remiremont\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/vosgesinfo.fr\/remiremontinfo\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/vosgesinfo.fr\/remiremontinfo\/#organization\",\"name\":\"Remiremont Info\",\"url\":\"https:\/\/vosgesinfo.fr\/remiremontinfo\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/vosgesinfo.fr\/remiremontinfo\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/5\/2023\/08\/favicon-remiremontinfo.png\",\"contentUrl\":\"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/5\/2023\/08\/favicon-remiremontinfo.png\",\"width\":512,\"height\":512,\"caption\":\"Remiremont Info\"},\"image\":{\"@id\":\"https:\/\/vosgesinfo.fr\/remiremontinfo\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/remiremontinfo\",\"https:\/\/x.com\/VosgesInfo88\",\"https:\/\/www.youtube.com\/@vosgesinfo\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/vosgesinfo.fr\/remiremontinfo\/#\/schema\/person\/3bfd164d5218a185b1db68655a265316\",\"name\":\"C D\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/vosgesinfo.fr\/remiremontinfo\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1f9a70007336511a47468b8f1c66f922b8b7cf617b02a31149ada43893a5d48f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1f9a70007336511a47468b8f1c66f922b8b7cf617b02a31149ada43893a5d48f?s=96&d=mm&r=g\",\"caption\":\"C D\"},\"url\":\"https:\/\/vosgesinfo.fr\/remiremontinfo\/author\/cedric-drevet\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Saint-Nabord\u00a0: inauguration des nouveaux \u00e9quipements sportifs sur le site des Perrey et de l'Arboretum - Remiremont Info","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vosgesinfo.fr\/remiremontinfo\/2021\/07\/saint-nabord-inauguration-nouveaux-equipements-sportifs-site-perrey-de-larboretum\/","twitter_card":"summary_large_image","twitter_title":"Saint-Nabord\u00a0: inauguration des nouveaux \u00e9quipements sportifs sur le site des Perrey et de l'Arboretum - Remiremont Info","twitter_description":"Une fen\u00eatre de ciel bleu s\u2019est ouverte ce samedi matin, au-dessus de Saint-Nabord pour l\u2019inauguration des nouveaux \u00e9quipements sportifs fra\u00eechement [&hellip;]","twitter_image":"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/5\/2024\/09\/202107224093818-381239876858402-7119046583882812857-n1.jpg","twitter_creator":"@VosgesInfo88","twitter_site":"@VosgesInfo88","twitter_misc":{"\u00c9crit par":"C D","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vosgesinfo.fr\/remiremontinfo\/2021\/07\/saint-nabord-inauguration-nouveaux-equipements-sportifs-site-perrey-de-larboretum\/#article","isPartOf":{"@id":"https:\/\/vosgesinfo.fr\/remiremontinfo\/2021\/07\/saint-nabord-inauguration-nouveaux-equipements-sportifs-site-perrey-de-larboretum\/"},"author":{"name":"C D","@id":"https:\/\/vosgesinfo.fr\/remiremontinfo\/#\/schema\/person\/3bfd164d5218a185b1db68655a265316"},"headline":"Saint-Nabord\u00a0: inauguration des nouveaux \u00e9quipements sportifs sur le site des Perrey et de l&rsquo;Arboretum","datePublished":"2021-07-26T02:59:52+00:00","dateModified":"2021-07-26T02:59:52+00:00","mainEntityOfPage":{"@id":"https:\/\/vosgesinfo.fr\/remiremontinfo\/2021\/07\/saint-nabord-inauguration-nouveaux-equipements-sportifs-site-perrey-de-larboretum\/"},"wordCount":464,"commentCount":0,"publisher":{"@id":"https:\/\/vosgesinfo.fr\/remiremontinfo\/#organization"},"image":{"@id":"https:\/\/vosgesinfo.fr\/remiremontinfo\/2021\/07\/saint-nabord-inauguration-nouveaux-equipements-sportifs-site-perrey-de-larboretum\/#primaryimage"},"thumbnailUrl":"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/5\/2024\/09\/202107224093818-381239876858402-7119046583882812857-n1.jpg","articleSection":["A la Une","Remiremont &amp; son canton","Saint-Nabord"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vosgesinfo.fr\/remiremontinfo\/2021\/07\/saint-nabord-inauguration-nouveaux-equipements-sportifs-site-perrey-de-larboretum\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vosgesinfo.fr\/remiremontinfo\/2021\/07\/saint-nabord-inauguration-nouveaux-equipements-sportifs-site-perrey-de-larboretum\/","url":"https:\/\/vosgesinfo.fr\/remiremontinfo\/2021\/07\/saint-nabord-inauguration-nouveaux-equipements-sportifs-site-perrey-de-larboretum\/","name":"Saint-Nabord\u00a0: inauguration des nouveaux \u00e9quipements sportifs sur le site des Perrey et de l'Arboretum - Remiremont Info","isPartOf":{"@id":"https:\/\/vosgesinfo.fr\/remiremontinfo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vosgesinfo.fr\/remiremontinfo\/2021\/07\/saint-nabord-inauguration-nouveaux-equipements-sportifs-site-perrey-de-larboretum\/#primaryimage"},"image":{"@id":"https:\/\/vosgesinfo.fr\/remiremontinfo\/2021\/07\/saint-nabord-inauguration-nouveaux-equipements-sportifs-site-perrey-de-larboretum\/#primaryimage"},"thumbnailUrl":"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/5\/2024\/09\/202107224093818-381239876858402-7119046583882812857-n1.jpg","datePublished":"2021-07-26T02:59:52+00:00","dateModified":"2021-07-26T02:59:52+00:00","breadcrumb":{"@id":"https:\/\/vosgesinfo.fr\/remiremontinfo\/2021\/07\/saint-nabord-inauguration-nouveaux-equipements-sportifs-site-perrey-de-larboretum\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vosgesinfo.fr\/remiremontinfo\/2021\/07\/saint-nabord-inauguration-nouveaux-equipements-sportifs-site-perrey-de-larboretum\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vosgesinfo.fr\/remiremontinfo\/2021\/07\/saint-nabord-inauguration-nouveaux-equipements-sportifs-site-perrey-de-larboretum\/#primaryimage","url":"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/5\/2024\/09\/202107224093818-381239876858402-7119046583882812857-n1.jpg","contentUrl":"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/5\/2024\/09\/202107224093818-381239876858402-7119046583882812857-n1.jpg","width":800,"height":625},{"@type":"BreadcrumbList","@id":"https:\/\/vosgesinfo.fr\/remiremontinfo\/2021\/07\/saint-nabord-inauguration-nouveaux-equipements-sportifs-site-perrey-de-larboretum\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/vosgesinfo.fr\/remiremontinfo\/"},{"@type":"ListItem","position":2,"name":"Saint-Nabord\u00a0: inauguration des nouveaux \u00e9quipements sportifs sur le site des Perrey et de l&rsquo;Arboretum"}]},{"@type":"WebSite","@id":"https:\/\/vosgesinfo.fr\/remiremontinfo\/#website","url":"https:\/\/vosgesinfo.fr\/remiremontinfo\/","name":"Remiremont Info","description":"Toute l&#039;actualit\u00e9 de Remiremont","publisher":{"@id":"https:\/\/vosgesinfo.fr\/remiremontinfo\/#organization"},"alternateName":"Toute l'actualit\u00e9 de Remiremont","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vosgesinfo.fr\/remiremontinfo\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/vosgesinfo.fr\/remiremontinfo\/#organization","name":"Remiremont Info","url":"https:\/\/vosgesinfo.fr\/remiremontinfo\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vosgesinfo.fr\/remiremontinfo\/#\/schema\/logo\/image\/","url":"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/5\/2023\/08\/favicon-remiremontinfo.png","contentUrl":"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/5\/2023\/08\/favicon-remiremontinfo.png","width":512,"height":512,"caption":"Remiremont Info"},"image":{"@id":"https:\/\/vosgesinfo.fr\/remiremontinfo\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/remiremontinfo","https:\/\/x.com\/VosgesInfo88","https:\/\/www.youtube.com\/@vosgesinfo"]},{"@type":"Person","@id":"https:\/\/vosgesinfo.fr\/remiremontinfo\/#\/schema\/person\/3bfd164d5218a185b1db68655a265316","name":"C D","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vosgesinfo.fr\/remiremontinfo\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1f9a70007336511a47468b8f1c66f922b8b7cf617b02a31149ada43893a5d48f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1f9a70007336511a47468b8f1c66f922b8b7cf617b02a31149ada43893a5d48f?s=96&d=mm&r=g","caption":"C D"},"url":"https:\/\/vosgesinfo.fr\/remiremontinfo\/author\/cedric-drevet\/"}]}},"_links":{"self":[{"href":"https:\/\/vosgesinfo.fr\/remiremontinfo\/wp-json\/wp\/v2\/posts\/43938","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vosgesinfo.fr\/remiremontinfo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vosgesinfo.fr\/remiremontinfo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vosgesinfo.fr\/remiremontinfo\/wp-json\/wp\/v2\/users\/407"}],"replies":[{"embeddable":true,"href":"https:\/\/vosgesinfo.fr\/remiremontinfo\/wp-json\/wp\/v2\/comments?post=43938"}],"version-history":[{"count":0,"href":"https:\/\/vosgesinfo.fr\/remiremontinfo\/wp-json\/wp\/v2\/posts\/43938\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vosgesinfo.fr\/remiremontinfo\/wp-json\/wp\/v2\/media\/43939"}],"wp:attachment":[{"href":"https:\/\/vosgesinfo.fr\/remiremontinfo\/wp-json\/wp\/v2\/media?parent=43938"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vosgesinfo.fr\/remiremontinfo\/wp-json\/wp\/v2\/categories?post=43938"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vosgesinfo.fr\/remiremontinfo\/wp-json\/wp\/v2\/tags?post=43938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}