{"id":48955,"date":"2021-11-18T08:45:49","date_gmt":"2021-11-18T07:45:49","guid":{"rendered":"https:\/\/vosgesinfo.fr\/remiremontinfo\/2021\/11\/37eme-collecte-nationale-banque-alimentaire-vosges-bientot-vos-magasins\/"},"modified":"2021-11-18T08:45:49","modified_gmt":"2021-11-18T07:45:49","slug":"37eme-collecte-nationale-banque-alimentaire-vosges-bientot-vos-magasins","status":"publish","type":"post","link":"https:\/\/vosgesinfo.fr\/remiremontinfo\/2021\/11\/37eme-collecte-nationale-banque-alimentaire-vosges-bientot-vos-magasins\/","title":{"rendered":"37\u00e8me Collecte Nationale : La Banque Alimentaire des Vosges bient\u00f4t dans vos magasins"},"content":{"rendered":"<p><a href=\"https:\/\/epinalinfos.fr\/wp-content\/uploads\/2018\/12\/banque-alimentaire.jpg\" data-featherlight=\"image\"><img decoding=\"async\" class=\"size-full wp-image-146412\" src=\"https:\/\/epinalinfos.fr\/wp-content\/uploads\/2018\/12\/banque-alimentaire.jpg\" alt=\"(cr\u00e9dit photo Banque alimentaire)\" width=\"577\" height=\"385\" \/><\/a><\/p>\n<h2><span style=\"font-size: 12pt;\">Les 26 et 27 novembre, la Banque Alimentaire des Vosges collectera dans les magasins du d\u00e9partement les dons de produits des particuliers. En compl\u00e9ment, la plateforme de dons en ligne monpaniersolidaire.org vient d\u2019\u00eatre lanc\u00e9e.<\/span><\/h2>\n<h3><span style=\"font-size: 12pt;\">La Collecte Nationale, le compl\u00e9ment indispensable d\u2019un travail quotidien<\/span><\/h3>\n<p><span style=\"font-size: 12pt;\">La Collecte Nationale des Banques Alimentaires sera lanc\u00e9e le 26 novembre prochain. Ce grand rendez-vous solidaire et citoyen permet au r\u00e9seau de collecter aupr\u00e8s du grand public 11% des produits distribu\u00e9s. Elle compl\u00e8te et diversifie les denr\u00e9es apport\u00e9es toute l\u2019ann\u00e9e par la Banque Alimentaire des Vosges aux personnes accueillies. Pr\u00e9sents dans 38 magasins, les b\u00e9n\u00e9voles en gilet orange r\u00e9cup\u00e9reront vos dons \u00e0 la sortie des caisses.<\/span><\/p>\n<h3><span style=\"font-size: 12pt;\">Monpaniersolidaire.org : en ligne du 15 novembre \u00e0 d\u00e9but d\u00e9cembre<\/span><\/h3>\n<p><span style=\"font-size: 12pt;\">D\u2019ores et d\u00e9j\u00e0 et pour la deuxi\u00e8me ann\u00e9e cons\u00e9cutive, les donateurs peuvent composer leur panier \u00e0 offrir sur monpaniersolidaire.org et ainsi participer \u00e0 la Collecte Nationale en ligne. Ce don financier sera consacr\u00e9 \u00e0 l\u2019achat de denr\u00e9es. Avec une nouveaut\u00e9 cette ann\u00e9e : 5 marques partenaires des Banques Alimentaires s\u2019associent \u00e0 la g\u00e9n\u00e9rosit\u00e9 du grand public et font don de produits alimentaires selon les besoins du r\u00e9seau.<\/span><\/p>\n<h3><span style=\"font-size: 12pt;\">Faire face \u00e0 une demande croissante<\/span><\/h3>\n<p><span style=\"font-size: 12pt;\">A l\u2019heure o\u00f9 les tarifs de l\u2019\u00e9nergie et les prix de l\u2019alimentation s\u2019envolent, la solidarit\u00e9 de chacun est en effet indispensable pour faire face \u00e0 une demande d\u2019aide alimentaire croissante. \u00ab\u00a0En 2020, le nombre des b\u00e9n\u00e9ficiaires soutenus par la Banque Alimentaire des Vosges a augment\u00e9 de 6 %\u201d, pr\u00e9cise Jean-Louis Rodier, Pr\u00e9sident de la Banque Alimentaire des Vosges.\u00a0<em>\u201cNous ne devons pas rel\u00e2cher nos efforts de solidarit\u00e9 et nous devons nous mobiliser pour que la Collecte Nationale permette de faire face aux besoins grandissants. C\u2019est pourquoi, nous faisons appel \u00e0 la g\u00e9n\u00e9rosit\u00e9 de tous.\u00a0\u00bb\u00a0<\/em><\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les 26 et 27 novembre, la Banque Alimentaire des Vosges collectera dans les magasins du d\u00e9partement les dons de produits [&hellip;]<\/p>\n","protected":false},"author":407,"featured_media":48956,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26,17,18],"tags":[2783,2103,32],"class_list":["post-48955","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-la-une","category-vie-associative","category-vosges","tag-banque-alimentaire","tag-collecte","tag-vosges"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>37\u00e8me Collecte Nationale : La Banque Alimentaire des Vosges bient\u00f4t dans vos magasins - Remiremont Info<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vosgesinfo.fr\/remiremontinfo\/2021\/11\/37eme-collecte-nationale-banque-alimentaire-vosges-bientot-vos-magasins\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"37\u00e8me Collecte Nationale : La Banque Alimentaire des Vosges bient\u00f4t dans vos magasins - Remiremont Info\" \/>\n<meta name=\"twitter:description\" content=\"Les 26 et 27 novembre, la Banque Alimentaire des Vosges collectera dans les magasins du d\u00e9partement les dons de produits [&hellip;]\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/5\/2024\/09\/202111banque-alimentaire.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@VosgesInfo88\" \/>\n<meta name=\"twitter:site\" content=\"@VosgesInfo88\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"C D\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/vosgesinfo.fr\/remiremontinfo\/2021\/11\/37eme-collecte-nationale-banque-alimentaire-vosges-bientot-vos-magasins\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/vosgesinfo.fr\/remiremontinfo\/2021\/11\/37eme-collecte-nationale-banque-alimentaire-vosges-bientot-vos-magasins\/\"},\"author\":{\"name\":\"C D\",\"@id\":\"https:\/\/vosgesinfo.fr\/remiremontinfo\/#\/schema\/person\/3bfd164d5218a185b1db68655a265316\"},\"headline\":\"37\u00e8me Collecte Nationale : La Banque Alimentaire des Vosges bient\u00f4t dans vos magasins\",\"datePublished\":\"2021-11-18T07:45:49+00:00\",\"dateModified\":\"2021-11-18T07:45:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/vosgesinfo.fr\/remiremontinfo\/2021\/11\/37eme-collecte-nationale-banque-alimentaire-vosges-bientot-vos-magasins\/\"},\"wordCount\":329,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/vosgesinfo.fr\/remiremontinfo\/#organization\"},\"image\":{\"@id\":\"https:\/\/vosgesinfo.fr\/remiremontinfo\/2021\/11\/37eme-collecte-nationale-banque-alimentaire-vosges-bientot-vos-magasins\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/5\/2024\/09\/202111banque-alimentaire.jpg\",\"keywords\":[\"banque alimentaire\",\"collecte\",\"Vosges\"],\"articleSection\":[\"A la Une\",\"Vie associative\",\"Vosges\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/vosgesinfo.fr\/remiremontinfo\/2021\/11\/37eme-collecte-nationale-banque-alimentaire-vosges-bientot-vos-magasins\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/vosgesinfo.fr\/remiremontinfo\/2021\/11\/37eme-collecte-nationale-banque-alimentaire-vosges-bientot-vos-magasins\/\",\"url\":\"https:\/\/vosgesinfo.fr\/remiremontinfo\/2021\/11\/37eme-collecte-nationale-banque-alimentaire-vosges-bientot-vos-magasins\/\",\"name\":\"37\u00e8me Collecte Nationale : La Banque Alimentaire des Vosges bient\u00f4t dans vos magasins - Remiremont Info\",\"isPartOf\":{\"@id\":\"https:\/\/vosgesinfo.fr\/remiremontinfo\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/vosgesinfo.fr\/remiremontinfo\/2021\/11\/37eme-collecte-nationale-banque-alimentaire-vosges-bientot-vos-magasins\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/vosgesinfo.fr\/remiremontinfo\/2021\/11\/37eme-collecte-nationale-banque-alimentaire-vosges-bientot-vos-magasins\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/5\/2024\/09\/202111banque-alimentaire.jpg\",\"datePublished\":\"2021-11-18T07:45:49+00:00\",\"dateModified\":\"2021-11-18T07:45:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/vosgesinfo.fr\/remiremontinfo\/2021\/11\/37eme-collecte-nationale-banque-alimentaire-vosges-bientot-vos-magasins\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/vosgesinfo.fr\/remiremontinfo\/2021\/11\/37eme-collecte-nationale-banque-alimentaire-vosges-bientot-vos-magasins\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/vosgesinfo.fr\/remiremontinfo\/2021\/11\/37eme-collecte-nationale-banque-alimentaire-vosges-bientot-vos-magasins\/#primaryimage\",\"url\":\"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/5\/2024\/09\/202111banque-alimentaire.jpg\",\"contentUrl\":\"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/5\/2024\/09\/202111banque-alimentaire.jpg\",\"width\":577,\"height\":385},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/vosgesinfo.fr\/remiremontinfo\/2021\/11\/37eme-collecte-nationale-banque-alimentaire-vosges-bientot-vos-magasins\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/vosgesinfo.fr\/remiremontinfo\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"37\u00e8me Collecte Nationale : La Banque Alimentaire des Vosges bient\u00f4t dans vos magasins\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/vosgesinfo.fr\/remiremontinfo\/#website\",\"url\":\"https:\/\/vosgesinfo.fr\/remiremontinfo\/\",\"name\":\"Remiremont Info\",\"description\":\"Toute l&#039;actualit\u00e9 de Remiremont\",\"publisher\":{\"@id\":\"https:\/\/vosgesinfo.fr\/remiremontinfo\/#organization\"},\"alternateName\":\"Toute l'actualit\u00e9 de Remiremont\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/vosgesinfo.fr\/remiremontinfo\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/vosgesinfo.fr\/remiremontinfo\/#organization\",\"name\":\"Remiremont Info\",\"url\":\"https:\/\/vosgesinfo.fr\/remiremontinfo\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/vosgesinfo.fr\/remiremontinfo\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/5\/2023\/08\/favicon-remiremontinfo.png\",\"contentUrl\":\"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/5\/2023\/08\/favicon-remiremontinfo.png\",\"width\":512,\"height\":512,\"caption\":\"Remiremont Info\"},\"image\":{\"@id\":\"https:\/\/vosgesinfo.fr\/remiremontinfo\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/remiremontinfo\",\"https:\/\/x.com\/VosgesInfo88\",\"https:\/\/www.youtube.com\/@vosgesinfo\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/vosgesinfo.fr\/remiremontinfo\/#\/schema\/person\/3bfd164d5218a185b1db68655a265316\",\"name\":\"C D\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/vosgesinfo.fr\/remiremontinfo\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1f9a70007336511a47468b8f1c66f922b8b7cf617b02a31149ada43893a5d48f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1f9a70007336511a47468b8f1c66f922b8b7cf617b02a31149ada43893a5d48f?s=96&d=mm&r=g\",\"caption\":\"C D\"},\"url\":\"https:\/\/vosgesinfo.fr\/remiremontinfo\/author\/cedric-drevet\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"37\u00e8me Collecte Nationale : La Banque Alimentaire des Vosges bient\u00f4t dans vos magasins - Remiremont Info","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vosgesinfo.fr\/remiremontinfo\/2021\/11\/37eme-collecte-nationale-banque-alimentaire-vosges-bientot-vos-magasins\/","twitter_card":"summary_large_image","twitter_title":"37\u00e8me Collecte Nationale : La Banque Alimentaire des Vosges bient\u00f4t dans vos magasins - Remiremont Info","twitter_description":"Les 26 et 27 novembre, la Banque Alimentaire des Vosges collectera dans les magasins du d\u00e9partement les dons de produits [&hellip;]","twitter_image":"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/5\/2024\/09\/202111banque-alimentaire.jpg","twitter_creator":"@VosgesInfo88","twitter_site":"@VosgesInfo88","twitter_misc":{"\u00c9crit par":"C D","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vosgesinfo.fr\/remiremontinfo\/2021\/11\/37eme-collecte-nationale-banque-alimentaire-vosges-bientot-vos-magasins\/#article","isPartOf":{"@id":"https:\/\/vosgesinfo.fr\/remiremontinfo\/2021\/11\/37eme-collecte-nationale-banque-alimentaire-vosges-bientot-vos-magasins\/"},"author":{"name":"C D","@id":"https:\/\/vosgesinfo.fr\/remiremontinfo\/#\/schema\/person\/3bfd164d5218a185b1db68655a265316"},"headline":"37\u00e8me Collecte Nationale : La Banque Alimentaire des Vosges bient\u00f4t dans vos magasins","datePublished":"2021-11-18T07:45:49+00:00","dateModified":"2021-11-18T07:45:49+00:00","mainEntityOfPage":{"@id":"https:\/\/vosgesinfo.fr\/remiremontinfo\/2021\/11\/37eme-collecte-nationale-banque-alimentaire-vosges-bientot-vos-magasins\/"},"wordCount":329,"commentCount":0,"publisher":{"@id":"https:\/\/vosgesinfo.fr\/remiremontinfo\/#organization"},"image":{"@id":"https:\/\/vosgesinfo.fr\/remiremontinfo\/2021\/11\/37eme-collecte-nationale-banque-alimentaire-vosges-bientot-vos-magasins\/#primaryimage"},"thumbnailUrl":"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/5\/2024\/09\/202111banque-alimentaire.jpg","keywords":["banque alimentaire","collecte","Vosges"],"articleSection":["A la Une","Vie associative","Vosges"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vosgesinfo.fr\/remiremontinfo\/2021\/11\/37eme-collecte-nationale-banque-alimentaire-vosges-bientot-vos-magasins\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vosgesinfo.fr\/remiremontinfo\/2021\/11\/37eme-collecte-nationale-banque-alimentaire-vosges-bientot-vos-magasins\/","url":"https:\/\/vosgesinfo.fr\/remiremontinfo\/2021\/11\/37eme-collecte-nationale-banque-alimentaire-vosges-bientot-vos-magasins\/","name":"37\u00e8me Collecte Nationale : La Banque Alimentaire des Vosges bient\u00f4t dans vos magasins - Remiremont Info","isPartOf":{"@id":"https:\/\/vosgesinfo.fr\/remiremontinfo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vosgesinfo.fr\/remiremontinfo\/2021\/11\/37eme-collecte-nationale-banque-alimentaire-vosges-bientot-vos-magasins\/#primaryimage"},"image":{"@id":"https:\/\/vosgesinfo.fr\/remiremontinfo\/2021\/11\/37eme-collecte-nationale-banque-alimentaire-vosges-bientot-vos-magasins\/#primaryimage"},"thumbnailUrl":"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/5\/2024\/09\/202111banque-alimentaire.jpg","datePublished":"2021-11-18T07:45:49+00:00","dateModified":"2021-11-18T07:45:49+00:00","breadcrumb":{"@id":"https:\/\/vosgesinfo.fr\/remiremontinfo\/2021\/11\/37eme-collecte-nationale-banque-alimentaire-vosges-bientot-vos-magasins\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vosgesinfo.fr\/remiremontinfo\/2021\/11\/37eme-collecte-nationale-banque-alimentaire-vosges-bientot-vos-magasins\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vosgesinfo.fr\/remiremontinfo\/2021\/11\/37eme-collecte-nationale-banque-alimentaire-vosges-bientot-vos-magasins\/#primaryimage","url":"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/5\/2024\/09\/202111banque-alimentaire.jpg","contentUrl":"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/5\/2024\/09\/202111banque-alimentaire.jpg","width":577,"height":385},{"@type":"BreadcrumbList","@id":"https:\/\/vosgesinfo.fr\/remiremontinfo\/2021\/11\/37eme-collecte-nationale-banque-alimentaire-vosges-bientot-vos-magasins\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/vosgesinfo.fr\/remiremontinfo\/"},{"@type":"ListItem","position":2,"name":"37\u00e8me Collecte Nationale : La Banque Alimentaire des Vosges bient\u00f4t dans vos magasins"}]},{"@type":"WebSite","@id":"https:\/\/vosgesinfo.fr\/remiremontinfo\/#website","url":"https:\/\/vosgesinfo.fr\/remiremontinfo\/","name":"Remiremont Info","description":"Toute l&#039;actualit\u00e9 de Remiremont","publisher":{"@id":"https:\/\/vosgesinfo.fr\/remiremontinfo\/#organization"},"alternateName":"Toute l'actualit\u00e9 de Remiremont","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vosgesinfo.fr\/remiremontinfo\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/vosgesinfo.fr\/remiremontinfo\/#organization","name":"Remiremont Info","url":"https:\/\/vosgesinfo.fr\/remiremontinfo\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vosgesinfo.fr\/remiremontinfo\/#\/schema\/logo\/image\/","url":"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/5\/2023\/08\/favicon-remiremontinfo.png","contentUrl":"https:\/\/vosgesinfo.fr\/app\/uploads\/sites\/5\/2023\/08\/favicon-remiremontinfo.png","width":512,"height":512,"caption":"Remiremont Info"},"image":{"@id":"https:\/\/vosgesinfo.fr\/remiremontinfo\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/remiremontinfo","https:\/\/x.com\/VosgesInfo88","https:\/\/www.youtube.com\/@vosgesinfo"]},{"@type":"Person","@id":"https:\/\/vosgesinfo.fr\/remiremontinfo\/#\/schema\/person\/3bfd164d5218a185b1db68655a265316","name":"C D","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vosgesinfo.fr\/remiremontinfo\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1f9a70007336511a47468b8f1c66f922b8b7cf617b02a31149ada43893a5d48f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1f9a70007336511a47468b8f1c66f922b8b7cf617b02a31149ada43893a5d48f?s=96&d=mm&r=g","caption":"C D"},"url":"https:\/\/vosgesinfo.fr\/remiremontinfo\/author\/cedric-drevet\/"}]}},"_links":{"self":[{"href":"https:\/\/vosgesinfo.fr\/remiremontinfo\/wp-json\/wp\/v2\/posts\/48955","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vosgesinfo.fr\/remiremontinfo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vosgesinfo.fr\/remiremontinfo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vosgesinfo.fr\/remiremontinfo\/wp-json\/wp\/v2\/users\/407"}],"replies":[{"embeddable":true,"href":"https:\/\/vosgesinfo.fr\/remiremontinfo\/wp-json\/wp\/v2\/comments?post=48955"}],"version-history":[{"count":0,"href":"https:\/\/vosgesinfo.fr\/remiremontinfo\/wp-json\/wp\/v2\/posts\/48955\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vosgesinfo.fr\/remiremontinfo\/wp-json\/wp\/v2\/media\/48956"}],"wp:attachment":[{"href":"https:\/\/vosgesinfo.fr\/remiremontinfo\/wp-json\/wp\/v2\/media?parent=48955"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vosgesinfo.fr\/remiremontinfo\/wp-json\/wp\/v2\/categories?post=48955"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vosgesinfo.fr\/remiremontinfo\/wp-json\/wp\/v2\/tags?post=48955"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}